{"id":2306,"date":"2019-11-22T07:36:14","date_gmt":"2019-11-22T07:36:14","guid":{"rendered":"http:\/\/www.conservationpulse.com\/wp-content\/uploads\/2019\/11\/turtle_release_in_central_Vietnam-7.jpg"},"modified":"2019-11-22T07:38:24","modified_gmt":"2019-11-22T07:38:24","slug":"turtle_release_in_central_vietnam-7","status":"inherit","type":"attachment","link":"https:\/\/indomyanmarconservation.org\/my\/2019-11-release_turtles_in_central_vietnam\/turtle_release_in_central_vietnam-7\/","title":{"rendered":"turtle_release_in_central_Vietnam (7)"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-2306","attachment","type-attachment","status-inherit","hentry"],"translation":{"provider":"WPGlobus","version":"3.0.0","language":"my","enabled_languages":["en","vi","my"],"languages":{"en":{"title":true},"vi":{"title":false},"my":{"title":false}}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/indomyanmarconservation.org\/wp-content\/uploads\/2019\/11\/turtle_release_in_central_Vietnam-7-e1574408358459.jpg'><img decoding=\"async\" width=\"200\" height=\"300\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20width=&#39;200&#39;%20height=&#39;300&#39;%20viewBox%3D&#39;0%200%20200%20300&#39;%2F%3E\" data-czlz data-src=\"https:\/\/indomyanmarconservation.org\/wp-content\/uploads\/2019\/11\/turtle_release_in_central_Vietnam-7-e1574408358459-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" data-srcset=\"https:\/\/indomyanmarconservation.org\/wp-content\/uploads\/2019\/11\/turtle_release_in_central_Vietnam-7-e1574408358459-200x300.jpg 200w, https:\/\/indomyanmarconservation.org\/wp-content\/uploads\/2019\/11\/turtle_release_in_central_Vietnam-7-e1574408358459.jpg 533w\" data-sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Turtles were carried by traditional rattan basket into dense forest. Photo &#8230; <\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":533,"height":800,"file":"2019\/11\/turtle_release_in_central_Vietnam-7-e1574408358459.jpg","filesize":119843,"sizes":{"woocommerce_thumbnail":{"file":"turtle_release_in_central_Vietnam-7-e1574408358459-533x600.jpg","width":533,"height":600,"filesize":92839,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/indomyanmarconservation.org\/wp-content\/uploads\/2019\/11\/turtle_release_in_central_Vietnam-7-e1574408358459-533x600.jpg"},"woocommerce_gallery_thumbnail":{"file":"turtle_release_in_central_Vietnam-7-e1574408358459-100x100.jpg","width":100,"height":100,"filesize":4447,"mime_type":"image\/jpeg","source_url":"https:\/\/indomyanmarconservation.org\/wp-content\/uploads\/2019\/11\/turtle_release_in_central_Vietnam-7-e1574408358459-100x100.jpg"},"thumbnail":{"file":"turtle_release_in_central_Vietnam-7-e1574408358459-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/indomyanmarconservation.org\/wp-content\/uploads\/2019\/11\/turtle_release_in_central_Vietnam-7-e1574408358459-150x150.jpg"},"medium":{"file":"turtle_release_in_central_Vietnam-7-e1574408358459-200x300.jpg","width":200,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/indomyanmarconservation.org\/wp-content\/uploads\/2019\/11\/turtle_release_in_central_Vietnam-7-e1574408358459-200x300.jpg"},"medium_large":{"file":"turtle_release_in_central_Vietnam-7-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/indomyanmarconservation.org\/wp-content\/uploads\/2019\/11\/turtle_release_in_central_Vietnam-7-768x512.jpg"},"codevz_360_320":{"file":"turtle_release_in_central_Vietnam-7-e1574408358459-360x320.jpg","width":360,"height":320,"mime_type":"image\/jpeg","source_url":"https:\/\/indomyanmarconservation.org\/wp-content\/uploads\/2019\/11\/turtle_release_in_central_Vietnam-7-e1574408358459-360x320.jpg"},"codevz_600_600":{"file":"turtle_release_in_central_Vietnam-7-e1574408358459-533x600.jpg","width":533,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/indomyanmarconservation.org\/wp-content\/uploads\/2019\/11\/turtle_release_in_central_Vietnam-7-e1574408358459-533x600.jpg"},"codevz_1200_200":{"file":"turtle_release_in_central_Vietnam-7-e1574408358459-533x200.jpg","width":533,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/indomyanmarconservation.org\/wp-content\/uploads\/2019\/11\/turtle_release_in_central_Vietnam-7-e1574408358459-533x200.jpg"},"codevz_1200_500":{"file":"turtle_release_in_central_Vietnam-7-e1574408358459-533x500.jpg","width":533,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/indomyanmarconservation.org\/wp-content\/uploads\/2019\/11\/turtle_release_in_central_Vietnam-7-e1574408358459-533x500.jpg"},"codevz_600_1000":{"file":"turtle_release_in_central_Vietnam-7-600x533.jpg","width":600,"height":533,"mime_type":"image\/jpeg","source_url":"https:\/\/indomyanmarconservation.org\/wp-content\/uploads\/2019\/11\/turtle_release_in_central_Vietnam-7-600x533.jpg"},"codevz_600_9999":{"file":"turtle_release_in_central_Vietnam-7-600x400.jpg","width":600,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/indomyanmarconservation.org\/wp-content\/uploads\/2019\/11\/turtle_release_in_central_Vietnam-7-600x400.jpg"},"woocommerce_single":{"file":"turtle_release_in_central_Vietnam-7-600x400.jpg","width":600,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/indomyanmarconservation.org\/wp-content\/uploads\/2019\/11\/turtle_release_in_central_Vietnam-7-e1574408358459.jpg"},"shop_catalog":{"file":"turtle_release_in_central_Vietnam-7-e1574408358459-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/indomyanmarconservation.org\/wp-content\/uploads\/2019\/11\/turtle_release_in_central_Vietnam-7-e1574408358459-300x300.jpg"},"shop_single":{"file":"turtle_release_in_central_Vietnam-7-600x400.jpg","width":600,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/indomyanmarconservation.org\/wp-content\/uploads\/2019\/11\/turtle_release_in_central_Vietnam-7-600x400.jpg"},"shop_thumbnail":{"file":"turtle_release_in_central_Vietnam-7-e1574408358459-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/indomyanmarconservation.org\/wp-content\/uploads\/2019\/11\/turtle_release_in_central_Vietnam-7-e1574408358459-100x100.jpg"},"full":{"file":"turtle_release_in_central_Vietnam-7-e1574408358459.jpg","width":533,"height":800,"mime_type":"image\/jpeg","source_url":"https:\/\/indomyanmarconservation.org\/wp-content\/uploads\/2019\/11\/turtle_release_in_central_Vietnam-7-e1574408358459.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":2299,"source_url":"https:\/\/indomyanmarconservation.org\/wp-content\/uploads\/2019\/11\/turtle_release_in_central_Vietnam-7-e1574408358459.jpg","_links":{"self":[{"href":"https:\/\/indomyanmarconservation.org\/my\/wp-json\/wp\/v2\/media\/2306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/indomyanmarconservation.org\/my\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/indomyanmarconservation.org\/my\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/indomyanmarconservation.org\/my\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/indomyanmarconservation.org\/my\/wp-json\/wp\/v2\/comments?post=2306"}]}}